{"id":943,"date":"2017-04-11T11:37:17","date_gmt":"2017-04-11T11:37:17","guid":{"rendered":"http:\/\/www.funerariamonteiro.com\/?page_id=943\/"},"modified":"2017-05-25T15:28:08","modified_gmt":"2017-05-25T15:28:08","slug":"contacts","status":"publish","type":"page","link":"https:\/\/www.funerariamonteiro.com\/fr\/contacts\/","title":{"rendered":"Contacts"},"content":{"rendered":"<section class=\"padding_top_contactos row-equal-height row-content-middle overflow-hidden padding-two-tb sm-padding-two-tb xs-padding-two-tb\" ><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container purple-text-tm text-open-sans col-lg-6 col-md-12 col-xs-12 col-sm-12\"><div class=\"vc-column-innner-wrapper\"><div  class=\" texto_contact  \" ><h3 class=\"large-text\">SERVICE PERMANENT - 24H<\/h3>\n<p><strong class=\"large-text\">+351 227 860 010<\/strong><br \/>\n<strong class=\"large-text\">+351 916 997 492<\/strong><\/p>\n<h3>E-MAIL<\/h3>\n<p><a href=\"mailto:geral@funerariamonteiro.com\">geral@funerariamonteiro.com<\/a><\/p>\n<\/div><a  href=\"https:\/\/www.facebook.com\/TorcatoMonteiroFuneraria\/\" target=\"_blank\" class=\"inner-link social-icon button btn\" ><i class=\"fa fa-facebook btn-round\"><\/i><\/a><\/div><\/div><div class=\"wpb_column vc_column_container dir_contac col-lg-6 col-md-12 col-xs-12 col-sm-12\"><div class=\"vc-column-innner-wrapper\">[contact-form-7 id=\"959\"]<\/div><\/div><\/div><\/div><\/section><section class=\" no-padding-top sm-no-padding-top xs-no-padding-top\" ><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container col-lg-4 col-md-12 col-xs-mobile-fullwidth col-sm-4 padding-two-lr sm-padding-two-lr xs-padding-two-lr\"><div class=\"vc-column-innner-wrapper\"><h3>SI\u00c8GE\/ Oliveira do Douro<\/h3>\n<p>Rua Rocha Silvestre, 301<br \/>\n4430-512 - Vila Nova de Gaia<br \/>\nTel.: +351 227 860 010<\/p>\n<div id=\"map\" class=\"map\"><\/div>\n<\/div><\/div><div class=\"wpb_column vc_column_container col-lg-4 col-md-12 col-xs-mobile-fullwidth col-sm-4 padding-two-lr sm-padding-two-lr xs-padding-two-lr\"><div class=\"vc-column-innner-wrapper\"><h3>SUCCURSALE 1 \/ Mafamude e Vilar do Para\u00edso<\/h3>\n<p>Rua Soares Reis, 715\/7<br \/>\n4400-317 Vila Nova de Gaia<br \/>\nTel.: +351 223 752 727<\/p>\n<div id=\"map2\" class=\"map\"><\/div>\n<\/div><\/div><div class=\"wpb_column vc_column_container col-lg-4 col-md-12 col-xs-mobile-fullwidth col-sm-4 padding-two-lr sm-padding-two-lr xs-padding-two-lr\"><div class=\"vc-column-innner-wrapper\"><h3>SUCCURSALE 2 \/ Vilar de Andorinho<\/h3>\n<p>Rua Her\u00f3is Ultramar, 2148<br \/>\n4430-432 Vila Nova de Gaia<br \/>\nTel.: +351 227 820 014<\/p>\n<div id=\"map3\" class=\"map\"><\/div>\n<\/div><\/div><\/div><\/div><\/section><section  class=\" fix-background overflow-hidden margin-two sm-margin-two xs-margin-two padding-four-tb sm-padding-four-tb xs-padding-four-tb\"  style=\" background-image: url(https:\/\/www.funerariamonteiro.com\/wp-content\/uploads\/2017\/01\/slider-home3.jpg);  min-height:200px\"><div class=\"container\"><div class=\"row\"><div class=\"wpb_column vc_column_container col-lg-12 col-md-12 col-xs-12 col-sm-12\"><div class=\"vc-column-innner-wrapper\"><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>SERVICE PERMANENT &#8211; 24H +351 227 860 010 +351 916 997 492 E-MAIL geral@funerariamonteiro.com [contact-form-7 id=\u00a0\u00bb959&Prime;]SI\u00c8GE\/ Oliveira do Douro Rua Rocha Silvestre, 301 4430-512 &#8211; Vila Nova de Gaia Tel.: +351 227 860 010 SUCCURSALE 1 \/ Mafamude e Vilar do Para\u00edso Rua Soares Reis, 715\/7 4400-317 Vila Nova de Gaia Tel.: +351 223 752 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.funerariamonteiro.com\/fr\/wp-json\/wp\/v2\/pages\/943"}],"collection":[{"href":"https:\/\/www.funerariamonteiro.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.funerariamonteiro.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.funerariamonteiro.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.funerariamonteiro.com\/fr\/wp-json\/wp\/v2\/comments?post=943"}],"version-history":[{"count":5,"href":"https:\/\/www.funerariamonteiro.com\/fr\/wp-json\/wp\/v2\/pages\/943\/revisions"}],"predecessor-version":[{"id":1077,"href":"https:\/\/www.funerariamonteiro.com\/fr\/wp-json\/wp\/v2\/pages\/943\/revisions\/1077"}],"wp:attachment":[{"href":"https:\/\/www.funerariamonteiro.com\/fr\/wp-json\/wp\/v2\/media?parent=943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}